{"id":22839,"date":"2025-05-14T12:10:46","date_gmt":"2025-05-14T10:10:46","guid":{"rendered":"https:\/\/www.stoprodent.com\/?page_id=22839"},"modified":"2026-06-10T15:48:12","modified_gmt":"2026-06-10T13:48:12","slug":"affiliate-terms-and-conditions","status":"publish","type":"page","link":"https:\/\/www.oleaia.com\/ch-de\/affiliate-terms-and-conditions\/","title":{"rendered":"Allgemeine Gesch\u00e4ftsbedingungen f\u00fcr Partner"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Diese Allgemeinen Nutzungsbedingungen (im Folgenden \u201cAllgemeine Bedingungen\u201d) regeln das Vertragsverh\u00e4ltnis zwischen Ferber Enterprises O\u00dc mit Sitz in Tornim\u00e4e tn 5, 10145, Tallinn, Estland, eingetragen im estnischen Handelsregister unter der Nummer 17475718, mit der europ\u00e4ischen innergemeinschaftlichen Umsatzsteuer-Identifikationsnummer EE102979314 (im Folgenden als \u201cH\u00e4ndler\u201d oder \u201cwir\u201d bezeichnet), und jeder nat\u00fcrlichen oder juristischen Person, die als Werbepartner auf das Partnerprogramm zugreift (im Folgenden als \u201cPartner\u201d oder \u201cSie\u201d bezeichnet).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Teilnahme am Partnerprogramm setzt die vollst\u00e4ndige, uneingeschr\u00e4nkte und bedingungslose Annahme der vorliegenden Allgemeinen Gesch\u00e4ftsbedingungen durch den Partner voraus. Sollte der Partner diese Bedingungen nicht ausdr\u00fccklich und vollst\u00e4ndig akzeptieren, ist es ihm strengstens untersagt, sich f\u00fcr das besagte Programm anzumelden oder daran teilzunehmen, in welcher Form auch immer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Artikel 1. Genehmigung oder Ablehnung der Eintragung<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das VU beh\u00e4lt sich ausdr\u00fccklich das Recht vor, nach eigenem Ermessen und ohne Angabe von Gr\u00fcnden einen Antrag auf Mitgliedschaft im Partnerprogramm anzunehmen oder abzulehnen. Der H\u00e4ndler haftet nicht f\u00fcr Nachteile, direkte oder indirekte Sch\u00e4den oder den Verlust von Chancen, die sich aus einer solchen Ablehnung ergeben. Der Partner verzichtet ausdr\u00fccklich auf jegliche Ma\u00dfnahmen, Anspr\u00fcche oder Regressanspr\u00fcche gegen\u00fcber dem H\u00e4ndler f\u00fcr den Fall, dass sein Antrag abgelehnt wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Artikel 2. Haftung<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jede Handlung, Ver\u00f6ffentlichung, Aussage oder jedes Verhalten, das geeignet ist, den Ruf, das Image, die Rechte, die Interessen oder die Glaubw\u00fcrdigkeit des H\u00e4ndlers, seines Mutterunternehmens, seiner Tochtergesellschaften oder seiner Gesch\u00e4ftspartner zu sch\u00e4digen, sei es direkt oder indirekt, vors\u00e4tzlich oder unvors\u00e4tzlich, w\u00e4hrend der Laufzeit des Programms oder innerhalb von zehn (10) Jahren nach dessen Beendigung, f\u00fchrt dazu, dass der Partner als Vertragsstrafe eine nicht erm\u00e4\u00dfigbare Pauschalentsch\u00e4digung von einhunderttausend Euro (100.000 EUR) zahlen muss, unbeschadet etwaiger zus\u00e4tzlicher Sch\u00e4den, die der H\u00e4ndler als Entsch\u00e4digung f\u00fcr den erlittenen Schaden geltend machen kann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Artikel 3. Partnerlinks und Gutscheine<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr den Partner wird automatisch ein eindeutiger Partner-Link generiert, der der Nachverfolgung und Provisionszuweisung dient. Der Partner kann auch spezifische Links zu ausgew\u00e4hlten Produkten, Kollektionen oder Seiten erstellen. Wenn ein Nutzer auf mehrere Affiliate-Links hintereinander klickt, wird nur die letzte g\u00fcltige Interaktion f\u00fcr Verg\u00fctungszwecke gespeichert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pers\u00f6nliche Promotion-Codes k\u00f6nnen dem Partner gem\u00e4\u00df den auf seinem pers\u00f6nlichen Dashboard festgelegten Bedingungen zugewiesen werden. Verwendet ein Kunde gleichzeitig einen Affiliate-Link und einen mit dem Affiliate verkn\u00fcpften Promotion-Code, wird nur eine Provision gez\u00e4hlt, und eine doppelte Verg\u00fctung ist ausgeschlossen. Wenn kein Code ausdr\u00fccklich zugewiesen wurde, ist jede Verwendung oder Werbung f\u00fcr einen solchen Code durch den Partner strengstens untersagt.<br>Der Partner ist berechtigt, f\u00fcr die Produkte oder Dienstleistungen des H\u00e4ndlers \u00fcber verschiedene Kan\u00e4le zu werben, einschlie\u00dflich, aber nicht beschr\u00e4nkt auf digitale Plattformen (Facebook, Instagram usw.), Kleinanzeigenseiten, Printmedien oder jedes andere rechtm\u00e4\u00dfige Werbemittel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Artikel 4. Provisionen und Zahlungen<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Partner ist berechtigt, eine Provision f\u00fcr jede Transaktion zu erhalten, die von einem Kunden get\u00e4tigt wird, der \u00fcber seinen Partnerlink vermittelt wurde, vorausgesetzt, dass die Bestellung endg\u00fcltig best\u00e4tigt wurde und nicht Gegenstand einer Stornierung, eines Rechtsstreits, einer R\u00fcckbuchung oder eines Erstattungsantrags ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die H\u00f6he der Provision wird auf der Grundlage der geltenden Tarifstruktur ermittelt, die jederzeit auf dem Dashboard verf\u00fcgbar ist. Die Berechnung erfolgt auf der Grundlage des Nettobetrags der Bestellung, ohne Steuern, Versandkosten und andere Nebenkosten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Partner muss \u00fcber die vorgesehene Schnittstelle die f\u00fcr den Empfang der Zahlungen erforderlichen Bankdaten oder Identifikatoren angeben. Die Zahlung der f\u00e4lligen Betr\u00e4ge erfolgt nach dem im Leitfaden f\u00fcr Partner festgelegten Zeitplan. Betr\u00fcgerische Transaktionen oder solche, die gegen die Programmregeln versto\u00dfen, k\u00f6nnen nicht ausgezahlt werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Artikel 5. Marketinginstrument<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der H\u00e4ndler stellt dem Partner \u00fcber einen speziellen Bereich Werbematerialien (Banner, Logos, Kampagnenbilder usw.) zur Verf\u00fcgung. Diese Elemente d\u00fcrfen ausschlie\u00dflich im Rahmen des Programms und in \u00dcbereinstimmung mit den vom Merchant festgelegten Bedingungen verwendet werden. Jegliche missbr\u00e4uchliche Verwendung, unbefugte \u00c4nderung oder Weitergabe an Dritte ist untersagt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Artikel 6. Netz<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn die Option \"Netzwerk\" aktiviert ist, ist der Partner berechtigt, andere nachgeschaltete Partner zu werben. Der Empfehlungslink wird \u00fcber den pers\u00f6nlichen Bereich des Affiliates bereitgestellt. Wenn ein nachgelagerter Partner \u00fcber seine eigenen Kan\u00e4le Verk\u00e4ufe generiert, kann der vorgelagerte Partner eine sogenannte \"Netzwerk\"-Provision erhalten, die den geltenden Parametern unterliegt.<br>Jeder auf diese Weise neu registrierte Partner muss den Netzwerk-Link verwenden, um eine korrekte Zuordnung im System des H\u00e4ndlers zu gew\u00e4hrleisten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Artikel 7. Cookies<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Nachverfolgung der provisionsgenerierenden Aktivit\u00e4ten basiert auf der Verwendung von Cookies. Es liegt in der Verantwortung des Mitglieds, die Endnutzer unter Einhaltung der Datenschutzgesetze \u00fcber diese Bedingung zu informieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lehnt der Endnutzer Cookies ab oder l\u00f6scht er sie, kann kein Tracking stattfinden, was einen Verg\u00fctungsanspruch ausschlie\u00dft. Die G\u00fcltigkeitsdauer des Cookies wird bei der Anmeldung des Affiliates festgelegt und tritt mit dem ersten Klick auf den Link oder der Nutzung des Coupons in Kraft.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Artikel 8. Reihenfolge der freien Erzeugnisse<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jede Bestellung kostenloser Produkte durch den Partner beinhaltet die Verpflichtung, innerhalb von sieben (7) Tagen nach Erhalt wesentliche Werbeinhalte zu ver\u00f6ffentlichen (z. B. ein Video, einen Blogartikel, einen Beitrag in sozialen Medien usw.). Im Falle einer Verz\u00f6gerung wird automatisch eine Strafe von f\u00fcnfzig US-Dollar (USD 50) pro Tag verh\u00e4ngt, die von m\u00f6glichen Einnahmen abgezogen werden kann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wird die Werbever\u00f6ffentlichung nicht innerhalb einer H\u00f6chstfrist von achtundzwanzig (28) Tagen vorgenommen, gilt das Partnerprogramm als durch die Initiative des Partners beendet. Letzterer muss seinen vollen Nennwert der erhaltenen Produkte sowie eine pauschale K\u00fcndigungsstrafe von vierzehnhundert Euro (1.400 EUR) zur\u00fcckerstatten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die unbefugte Entfernung von bereits ver\u00f6ffentlichten Werbeinhalten wird als vom Partner veranlasste K\u00fcndigung mit den gleichen finanziellen Folgen betrachtet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Artikel 9. Wettbewerbsverbotsklausel<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">W\u00e4hrend der gesamten Teilnahme am Programm und f\u00fcr einen Zeitraum von einem (1) Jahr nach dessen Beendigung ist es dem Partner strengstens untersagt, direkt oder indirekt Produkte oder Dienstleistungen zu bewerben, die mit denen des H\u00e4ndlers konkurrieren. Nichteinhaltung dieser Klausel f\u00fchrt zu einer nicht reduzierbaren Pauschalstrafe von zwanzigtausend Euro (20.000 EUR) pro nachgewiesener Verletzung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Artikel 10. Frist f\u00fcr die Bef\u00f6rderung<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ab dem Datum der Registrierungsgenehmigung hat der Partner eine nicht verl\u00e4ngerbare Frist von achtundzwanzig (28) Tagen, um mindestens eine \u00f6ffentliche Mitteilung zu ver\u00f6ffentlichen, die die Marke des H\u00e4ndlers bewirbt. Erfolgt eine solche Werbung nicht innerhalb dieses Zeitraums, gilt das Programm automatisch als beendet, was ausschlie\u00dflich auf das Verschulden des Partners zur\u00fcckzuf\u00fchren ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Artikel 11. Beendigung<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jede K\u00fcndigung, sei sie durch den Partner oder den H\u00e4ndler veranlasst, f\u00fchrt zur Zahlung einer pauschalen Entsch\u00e4digung in H\u00f6he von vierzehnhundert Euro (1.400 EUR), unbeschadet bereits erhaltener oder f\u00e4lliger Betr\u00e4ge f\u00fcr Provisionen. Diese Entsch\u00e4digung kann von zuk\u00fcnftigen Einnahmen abgezogen oder im Falle eines unzureichenden Saldos eine R\u00fcckerstattung verlangt werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gegebenenfalls erstattet der Partner auch den vollen \u00f6ffentlichen Preis der zuvor erhaltenen Gratisprodukte. Die Beendigung des Programms entbindet den Partner nicht von seinen fr\u00fcheren Verpflichtungen, insbesondere nicht von denen, die sich auf Wettbewerbsverbote und Vertraulichkeitsklauseln beziehen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>These General Terms and Conditions of Use (hereinafter the \u201cGeneral Terms\u201d) govern the contractual relationship between Ferber Enterprises O\u00dc, whose registered office is located at Tornim\u00e4e tn 5, 10145, Tallinn, Estonia, registered in the Estonian Commercial Register under number 17475718, with European intra-community VAT number EE102979314 (hereinafter referred to as the \u201cMerchant\u201d or \u201cwe\u201d), and [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-22839","page","type-page","status-publish","hentry"],"spectra_custom_meta":{"_edit_lock":["1781317896:1"],"_uag_custom_page_level_css":[""],"site-sidebar-layout":["default"],"site-content-layout":[""],"ast-site-content-layout":["default"],"site-content-style":["default"],"site-sidebar-style":["default"],"ast-global-header-display":[""],"ast-banner-title-visibility":[""],"ast-main-header-display":[""],"ast-hfb-above-header-display":[""],"ast-hfb-below-header-display":[""],"ast-hfb-mobile-header-display":[""],"site-post-title":[""],"ast-breadcrumbs-content":[""],"ast-featured-img":[""],"footer-sml-layout":[""],"theme-transparent-header-meta":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"header-above-stick-meta":[""],"header-main-stick-meta":[""],"header-below-stick-meta":[""],"astra-migrate-meta-layouts":["set"],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"footnotes":[""],"_elementor_edit_mode":[""],"_elementor_template_type":[""],"_elementor_data":[""],"_elementor_conditions":["a:0:{}"],"rank_math_news_sitemap_robots":["index"],"rank_math_robots":["a:1:{i:0;s:5:\"index\";}"],"_edit_last":["1"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uag_css_file_name":["uag-css-22839.css"],"_uag_page_assets":["a:9:{s:3:\"css\";s:7133:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.uagb-block-e6f939b3.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:13:{i:0;s:14:\"core\/paragraph\";i:1;s:11:\"core\/search\";i:2;s:10:\"core\/group\";i:3;s:12:\"core\/heading\";i:4;s:17:\"core\/latest-posts\";i:5;s:20:\"core\/latest-comments\";i:6;s:13:\"core\/archives\";i:7;s:15:\"core\/categories\";i:8;s:10:\"uagb\/image\";i:9;s:11:\"core\/spacer\";i:10;s:30:\"woocommerce\/product-categories\";i:11;s:10:\"core\/image\";i:12;s:14:\"core\/shortcode\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1784147964\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/www.oleaia.com\/ch-de\/author\/admin2721\/"},"uagb_comment_info":0,"uagb_excerpt":"These General Terms and Conditions of Use (hereinafter the \u201cGeneral Terms\u201d) govern the contractual relationship between Ferber Enterprises O\u00dc, whose registered office is located at Tornim\u00e4e tn 5, 10145, Tallinn, Estonia, registered in the Estonian Commercial Register under number 17475718, with European intra-community VAT number EE102979314 (hereinafter referred to as the \u201cMerchant\u201d or \u201cwe\u201d), and&hellip;","_links":{"self":[{"href":"https:\/\/www.oleaia.com\/ch-de\/wp-json\/wp\/v2\/pages\/22839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oleaia.com\/ch-de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.oleaia.com\/ch-de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.oleaia.com\/ch-de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oleaia.com\/ch-de\/wp-json\/wp\/v2\/comments?post=22839"}],"version-history":[{"count":3,"href":"https:\/\/www.oleaia.com\/ch-de\/wp-json\/wp\/v2\/pages\/22839\/revisions"}],"predecessor-version":[{"id":85503,"href":"https:\/\/www.oleaia.com\/ch-de\/wp-json\/wp\/v2\/pages\/22839\/revisions\/85503"}],"wp:attachment":[{"href":"https:\/\/www.oleaia.com\/ch-de\/wp-json\/wp\/v2\/media?parent=22839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}